{"id":498347,"date":"2023-06-19T19:26:01","date_gmt":"2023-06-19T18:26:01","guid":{"rendered":"https:\/\/www.erothis.com\/?post_type=product&#038;p=498347"},"modified":"2026-05-08T09:31:29","modified_gmt":"2026-05-08T08:31:29","slug":"darkness-esposas-ancho-fino-texturizadas","status":"publish","type":"product","link":"https:\/\/www.erothis.com\/es\/productos\/darkness-esposas-ancho-fino-texturizadas\/","title":{"rendered":"DARKNESS &#8211; ESPOSAS  ANCHO FINO TEXTURIZADAS"},"content":{"rendered":"<p>Encierra a tu amante con estas esposas sexys, efectivas y c&oacute;modas. Un accesorio cl&aacute;sico para tus juegos de esclavitud.<\/p>\n<p>Estos pu&ntilde;os tienen la est&eacute;tica elegante que anhelas. Ancho fino en color negro texturizado y terminado con una hebilla, tu sumiso no podr&aacute; escapar. El interior suave garantiza que se mantendr&aacute;n c&oacute;modos sin importar cu&aacute;nto tiren o cu&aacute;nto tiempo juegues.<\/p>\n<ul>\n<li>Materila: PU, y metal<\/li>\n<li>Material libre de niquel.<\/li>\n<\/ul>\n<p>LA MARCA<\/p>\n<p>Darkness es una marca de nueva generaci&oacute;n 2020, todos nuestros materiales son de excelente calidad asegurando que la fabricaci&oacute;n compromete un resultado perfecto para principiantes o avanzados que le gusta el mundo Fetish o bdsm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DARKNESS &#8211; TEXTURED THIN HANDCUFFS<\/p>\n","protected":false},"featured_media":243295,"comment_status":"open","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[],"product_cat":[1252,1254],"product_tag":[],"class_list":["post-498347","product","type-product","status-publish","has-post-thumbnail","product_cat-bdsm-es","product_cat-esposas","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/product\/498347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/comments?post=498347"}],"version-history":[{"count":1,"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/product\/498347\/revisions"}],"predecessor-version":[{"id":498377,"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/product\/498347\/revisions\/498377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/media\/243295"}],"wp:attachment":[{"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/media?parent=498347"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/product_brand?post=498347"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/product_cat?post=498347"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.erothis.com\/es\/wp-json\/wp\/v2\/product_tag?post=498347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}